{"id":8999,"date":"2025-03-15T20:13:37","date_gmt":"2025-03-15T20:13:37","guid":{"rendered":"https:\/\/lavocedelpaese.info\/index.php\/2025\/03\/15\/volley-a3-al-via-lavventura-playoff-della-joy-volley\/"},"modified":"2025-03-15T20:13:37","modified_gmt":"2025-03-15T20:13:37","slug":"volley-a3-al-via-lavventura-playoff-della-joy-volley","status":"publish","type":"post","link":"https:\/\/lavocedelpaese.info\/index.php\/2025\/03\/15\/volley-a3-al-via-lavventura-playoff-della-joy-volley\/","title":{"rendered":"Volley A3. Al via l\u2019avventura playoff della Joy Volley\u00a0\u200b"},"content":{"rendered":"<p>\u00a0<\/p>\n<p>\u200b\u00a0<\/p>\n<p>\u200b\u00a0<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-5962 alignleft\" src=\"https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2025\/03\/VINCENZO-MASI.jpg\" alt=\"\" width=\"400\" height=\"300\"\/>\u201cSi accendono i riflettori sul cammino playoff della Joy Volley Gioia del Colle che domenica 16 marzo 2025, in occasione di gara 1 dei quarti di finale, ospiter\u00e0 la Sieco Service Ortona guidata dal tecnico pugliese Francesco Denora Caporusso.<\/p>\n<p>Conquistato il sesto posto nel girone Blu con il successo al tie-break ottenuto al PalaCalafiore di Reggio Calabria, la compagine abruzzese far\u00e0 il suo ritorno al PalaCapurso a distanza di oltre due mesi dal match perso contro capitan Mariano e compagni sul risultato finale di 3-0.<\/p>\n<p>La serie, che si decider\u00e0 al meglio delle tre gare, vedr\u00e0 contrapposte le due squadre per l\u2019ennesima volta in questa stagione, considerando gli allenamenti congiunti disputati in preseason e la gara di andata nel girone Blu, giocatasi al palasport comunale di Ortona e vinta al tie-break dalla Sieco Service.<br \/>\nDue formazioni che si conoscono bene, quindi, e che promettono di regalare spettacolo all\u2019impianto sportivo di via Einaudi, non solo alla luce degli importanti valori tecnici espressi dai propri organici ma anche della prestigiosa posta in palio nella serie (pass per le semifinali Play Off Serie A3 Credem Banca contro la vincente tra Belluno Volley e Monge Gerbaudo Savigliano).<\/p>\n<p>Reduci dalle ultime due sconfitte contro la Gaia Energy Napoli e l\u2019Avimecc Modica, i biancorossi vogliono vivere una grande serata dinanzi al proprio pubblico e iniziare nel migliore dei modi l\u2019avventura dei quarti di finale.<\/p>\n<p>Ortona sar\u00e0 sicuramente un ostacolo difficile da aggirare. Leonel Marshall \u00e8 la punta di diamante di un team competitivo che, approdato anche alla semifinale della Del Monte\u00ae Coppa Italia Serie A3 in questa stagione, annovera al suo interno altri atleti di grande esperienza come il palleggiatore Riccardo Pinelli e lo schiacciatore Matteo Bertoli.<\/p>\n<p>\u201cArriviamo a questo appuntamento importante della stagione al termine di un buon percorso in regular season, in un girone Blu altamente competitivo dominato dalla Romeo Sorrento, vincitrice anche della Del Monte\u00ae Coppa Italia \u2013 dichiara il direttore generale della Joy Volley <strong>Vincenzo Masi <\/strong>-. Al termine della regular season che, per quanto ci riguarda, \u00e8 stata condizionata da alcuni infortuni importanti, sento di dover rivolgere i complimenti a societ\u00e0, staff tecnico e atleti per l\u2019impegno profuso e la massima dedizione mostrata alla causa biancorossa. Nei quarti di finale ritroviamo la Sieco Service Ortona, una squadra molto competitiva che prover\u00e0 a metterci in difficolt\u00e0 sin da subito. Dal canto nostro, dovremo sfruttare al massimo il fattore campo, che \u00e8 dalla nostra parte in questa serie, ed esprimere la nostra pallavolo migliore \u2013 conclude -. Confido nel sostegno del nostro pubblico, dei tanti appassionati di pallavolo, auspicando di vivere insieme serate importanti in questa fase playoff\u201d.<\/p>\n<p>Gli arbitri dell\u2019incontro saranno <strong>Martin Polenta<\/strong> e <strong>Danilo Domenico De Sensi<\/strong>.<\/p>\n<p>A partire dalle ore 18:00, il match sar\u00e0 trasmesso in diretta sul canale YouTube della Lega Pallavolo Serie A e commentato dal telecronista Mimmo Guagnano\u201d.<\/p>\n<p><strong>Gianluca Falcone<\/strong><\/p>\n<p>Ufficio Stampa Joy Volley Gioia<\/p>\n<p><a class=\"a2a_button_facebook\" href=\"https:\/\/www.addtoany.com\/add_to\/facebook?linkurl=https%3A%2F%2Fgioia.lavocedelpaese.info%2Findex.php%2F2025%2F03%2F15%2Fvolley-a3-al-via-lavventura-playoff-della-joy-volley%2F&amp;linkname=Volley%20A3.%20Al%20via%20l%E2%80%99avventura%20playoff%20della%20Joy%20Volley\" title=\"Facebook\" rel=\"nofollow noopener\" target=\"_blank\"><\/a><a class=\"a2a_button_twitter\" href=\"https:\/\/www.addtoany.com\/add_to\/twitter?linkurl=https%3A%2F%2Fgioia.lavocedelpaese.info%2Findex.php%2F2025%2F03%2F15%2Fvolley-a3-al-via-lavventura-playoff-della-joy-volley%2F&amp;linkname=Volley%20A3.%20Al%20via%20l%E2%80%99avventura%20playoff%20della%20Joy%20Volley\" title=\"Twitter\" rel=\"nofollow noopener\" target=\"_blank\"><\/a><a class=\"a2a_button_whatsapp\" href=\"https:\/\/www.addtoany.com\/add_to\/whatsapp?linkurl=https%3A%2F%2Fgioia.lavocedelpaese.info%2Findex.php%2F2025%2F03%2F15%2Fvolley-a3-al-via-lavventura-playoff-della-joy-volley%2F&amp;linkname=Volley%20A3.%20Al%20via%20l%E2%80%99avventura%20playoff%20della%20Joy%20Volley\" title=\"WhatsApp\" rel=\"nofollow noopener\" target=\"_blank\"><\/a><a class=\"a2a_button_telegram\" href=\"https:\/\/www.addtoany.com\/add_to\/telegram?linkurl=https%3A%2F%2Fgioia.lavocedelpaese.info%2Findex.php%2F2025%2F03%2F15%2Fvolley-a3-al-via-lavventura-playoff-della-joy-volley%2F&amp;linkname=Volley%20A3.%20Al%20via%20l%E2%80%99avventura%20playoff%20della%20Joy%20Volley\" title=\"Telegram\" rel=\"nofollow noopener\" target=\"_blank\"><\/a><a class=\"a2a_button_email\" href=\"https:\/\/www.addtoany.com\/add_to\/email?linkurl=https%3A%2F%2Fgioia.lavocedelpaese.info%2Findex.php%2F2025%2F03%2F15%2Fvolley-a3-al-via-lavventura-playoff-della-joy-volley%2F&amp;linkname=Volley%20A3.%20Al%20via%20l%E2%80%99avventura%20playoff%20della%20Joy%20Volley\" title=\"Email\" rel=\"nofollow noopener\" target=\"_blank\"><\/a><\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u200b\u00a0\u00a0\u00a0<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u200b\u00a0 \u200b\u00a0 \u201cSi accendono i riflettori sul cammino playoff della Joy Volley Gioia del Colle che domenica 16 marzo<\/p>\n","protected":false},"author":6,"featured_media":9000,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[33],"tags":[],"class_list":["post-8999","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-network"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Volley A3. Al via l\u2019avventura playoff della Joy Volley\u00a0\u200b - La Voce del Paese<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lavocedelpaese.info\/index.php\/2025\/03\/15\/volley-a3-al-via-lavventura-playoff-della-joy-volley\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Volley A3. Al via l\u2019avventura playoff della Joy Volley\u00a0\u200b - La Voce del Paese\" \/>\n<meta property=\"og:description\" content=\"\u00a0 \u200b\u00a0 \u200b\u00a0 \u201cSi accendono i riflettori sul cammino playoff della Joy Volley Gioia del Colle che domenica 16 marzo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lavocedelpaese.info\/index.php\/2025\/03\/15\/volley-a3-al-via-lavventura-playoff-della-joy-volley\/\" \/>\n<meta property=\"og:site_name\" content=\"La Voce del Paese\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/lavocedelpaese.info\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-15T20:13:37+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/2025\\\/03\\\/15\\\/volley-a3-al-via-lavventura-playoff-della-joy-volley\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/2025\\\/03\\\/15\\\/volley-a3-al-via-lavventura-playoff-della-joy-volley\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/#\\\/schema\\\/person\\\/ec151d321306bd7591f7a061abf72d88\"},\"headline\":\"Volley A3. Al via l\u2019avventura playoff della Joy Volley\u00a0\u200b\",\"datePublished\":\"2025-03-15T20:13:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/2025\\\/03\\\/15\\\/volley-a3-al-via-lavventura-playoff-della-joy-volley\\\/\"},\"wordCount\":485,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/2025\\\/03\\\/15\\\/volley-a3-al-via-lavventura-playoff-della-joy-volley\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/VINCENZO-MASI-pwdg63.jpeg\",\"articleSection\":[\"network\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/2025\\\/03\\\/15\\\/volley-a3-al-via-lavventura-playoff-della-joy-volley\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/2025\\\/03\\\/15\\\/volley-a3-al-via-lavventura-playoff-della-joy-volley\\\/\",\"url\":\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/2025\\\/03\\\/15\\\/volley-a3-al-via-lavventura-playoff-della-joy-volley\\\/\",\"name\":\"Volley A3. Al via l\u2019avventura playoff della Joy Volley\u00a0\u200b - La Voce del Paese\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/2025\\\/03\\\/15\\\/volley-a3-al-via-lavventura-playoff-della-joy-volley\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/2025\\\/03\\\/15\\\/volley-a3-al-via-lavventura-playoff-della-joy-volley\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/VINCENZO-MASI-pwdg63.jpeg\",\"datePublished\":\"2025-03-15T20:13:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/2025\\\/03\\\/15\\\/volley-a3-al-via-lavventura-playoff-della-joy-volley\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/2025\\\/03\\\/15\\\/volley-a3-al-via-lavventura-playoff-della-joy-volley\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/2025\\\/03\\\/15\\\/volley-a3-al-via-lavventura-playoff-della-joy-volley\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/VINCENZO-MASI-pwdg63.jpeg\",\"contentUrl\":\"https:\\\/\\\/lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/VINCENZO-MASI-pwdg63.jpeg\",\"width\":1000,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/2025\\\/03\\\/15\\\/volley-a3-al-via-lavventura-playoff-della-joy-volley\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lavocedelpaese.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Volley A3. Al via l\u2019avventura playoff della Joy Volley\u00a0\u200b\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/#website\",\"url\":\"https:\\\/\\\/lavocedelpaese.info\\\/\",\"name\":\"La Voce del Paese\",\"description\":\"Un network di idee\",\"publisher\":{\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lavocedelpaese.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/#organization\",\"name\":\"La Voce del Paese\",\"url\":\"https:\\\/\\\/lavocedelpaese.info\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-logo-150-127.png\",\"contentUrl\":\"https:\\\/\\\/lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-logo-150-127.png\",\"width\":137,\"height\":119,\"caption\":\"La Voce del Paese\"},\"image\":{\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/lavocedelpaese.info\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/#\\\/schema\\\/person\\\/ec151d321306bd7591f7a061abf72d88\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af8f2caf0663124588de48a9380e07cbc95a74ef15b8062d0d39106c32fe3023?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af8f2caf0663124588de48a9380e07cbc95a74ef15b8062d0d39106c32fe3023?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af8f2caf0663124588de48a9380e07cbc95a74ef15b8062d0d39106c32fe3023?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/lavocedelpaese.info\"],\"url\":\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Volley A3. Al via l\u2019avventura playoff della Joy Volley\u00a0\u200b - La Voce del Paese","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lavocedelpaese.info\/index.php\/2025\/03\/15\/volley-a3-al-via-lavventura-playoff-della-joy-volley\/","og_locale":"it_IT","og_type":"article","og_title":"Volley A3. Al via l\u2019avventura playoff della Joy Volley\u00a0\u200b - La Voce del Paese","og_description":"\u00a0 \u200b\u00a0 \u200b\u00a0 \u201cSi accendono i riflettori sul cammino playoff della Joy Volley Gioia del Colle che domenica 16 marzo","og_url":"https:\/\/lavocedelpaese.info\/index.php\/2025\/03\/15\/volley-a3-al-via-lavventura-playoff-della-joy-volley\/","og_site_name":"La Voce del Paese","article_publisher":"https:\/\/www.facebook.com\/lavocedelpaese.info","article_published_time":"2025-03-15T20:13:37+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lavocedelpaese.info\/index.php\/2025\/03\/15\/volley-a3-al-via-lavventura-playoff-della-joy-volley\/#article","isPartOf":{"@id":"https:\/\/lavocedelpaese.info\/index.php\/2025\/03\/15\/volley-a3-al-via-lavventura-playoff-della-joy-volley\/"},"author":{"name":"admin","@id":"https:\/\/lavocedelpaese.info\/#\/schema\/person\/ec151d321306bd7591f7a061abf72d88"},"headline":"Volley A3. Al via l\u2019avventura playoff della Joy Volley\u00a0\u200b","datePublished":"2025-03-15T20:13:37+00:00","mainEntityOfPage":{"@id":"https:\/\/lavocedelpaese.info\/index.php\/2025\/03\/15\/volley-a3-al-via-lavventura-playoff-della-joy-volley\/"},"wordCount":485,"commentCount":0,"publisher":{"@id":"https:\/\/lavocedelpaese.info\/#organization"},"image":{"@id":"https:\/\/lavocedelpaese.info\/index.php\/2025\/03\/15\/volley-a3-al-via-lavventura-playoff-della-joy-volley\/#primaryimage"},"thumbnailUrl":"https:\/\/lavocedelpaese.info\/wp-content\/uploads\/2025\/03\/VINCENZO-MASI-pwdg63.jpeg","articleSection":["network"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lavocedelpaese.info\/index.php\/2025\/03\/15\/volley-a3-al-via-lavventura-playoff-della-joy-volley\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lavocedelpaese.info\/index.php\/2025\/03\/15\/volley-a3-al-via-lavventura-playoff-della-joy-volley\/","url":"https:\/\/lavocedelpaese.info\/index.php\/2025\/03\/15\/volley-a3-al-via-lavventura-playoff-della-joy-volley\/","name":"Volley A3. Al via l\u2019avventura playoff della Joy Volley\u00a0\u200b - La Voce del Paese","isPartOf":{"@id":"https:\/\/lavocedelpaese.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lavocedelpaese.info\/index.php\/2025\/03\/15\/volley-a3-al-via-lavventura-playoff-della-joy-volley\/#primaryimage"},"image":{"@id":"https:\/\/lavocedelpaese.info\/index.php\/2025\/03\/15\/volley-a3-al-via-lavventura-playoff-della-joy-volley\/#primaryimage"},"thumbnailUrl":"https:\/\/lavocedelpaese.info\/wp-content\/uploads\/2025\/03\/VINCENZO-MASI-pwdg63.jpeg","datePublished":"2025-03-15T20:13:37+00:00","breadcrumb":{"@id":"https:\/\/lavocedelpaese.info\/index.php\/2025\/03\/15\/volley-a3-al-via-lavventura-playoff-della-joy-volley\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lavocedelpaese.info\/index.php\/2025\/03\/15\/volley-a3-al-via-lavventura-playoff-della-joy-volley\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/lavocedelpaese.info\/index.php\/2025\/03\/15\/volley-a3-al-via-lavventura-playoff-della-joy-volley\/#primaryimage","url":"https:\/\/lavocedelpaese.info\/wp-content\/uploads\/2025\/03\/VINCENZO-MASI-pwdg63.jpeg","contentUrl":"https:\/\/lavocedelpaese.info\/wp-content\/uploads\/2025\/03\/VINCENZO-MASI-pwdg63.jpeg","width":1000,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/lavocedelpaese.info\/index.php\/2025\/03\/15\/volley-a3-al-via-lavventura-playoff-della-joy-volley\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lavocedelpaese.info\/"},{"@type":"ListItem","position":2,"name":"Volley A3. Al via l\u2019avventura playoff della Joy Volley\u00a0\u200b"}]},{"@type":"WebSite","@id":"https:\/\/lavocedelpaese.info\/#website","url":"https:\/\/lavocedelpaese.info\/","name":"La Voce del Paese","description":"Un network di idee","publisher":{"@id":"https:\/\/lavocedelpaese.info\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lavocedelpaese.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/lavocedelpaese.info\/#organization","name":"La Voce del Paese","url":"https:\/\/lavocedelpaese.info\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/lavocedelpaese.info\/#\/schema\/logo\/image\/","url":"https:\/\/lavocedelpaese.info\/wp-content\/uploads\/2023\/01\/cropped-logo-150-127.png","contentUrl":"https:\/\/lavocedelpaese.info\/wp-content\/uploads\/2023\/01\/cropped-logo-150-127.png","width":137,"height":119,"caption":"La Voce del Paese"},"image":{"@id":"https:\/\/lavocedelpaese.info\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/lavocedelpaese.info"]},{"@type":"Person","@id":"https:\/\/lavocedelpaese.info\/#\/schema\/person\/ec151d321306bd7591f7a061abf72d88","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/af8f2caf0663124588de48a9380e07cbc95a74ef15b8062d0d39106c32fe3023?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/af8f2caf0663124588de48a9380e07cbc95a74ef15b8062d0d39106c32fe3023?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/af8f2caf0663124588de48a9380e07cbc95a74ef15b8062d0d39106c32fe3023?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/lavocedelpaese.info"],"url":"https:\/\/lavocedelpaese.info\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/8999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/comments?post=8999"}],"version-history":[{"count":0,"href":"https:\/\/lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/8999\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media\/9000"}],"wp:attachment":[{"href":"https:\/\/lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media?parent=8999"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/categories?post=8999"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/tags?post=8999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}