{"id":1764,"date":"2023-07-18T18:26:09","date_gmt":"2023-07-18T18:26:09","guid":{"rendered":"https:\/\/lavocedelpaese.info\/index.php\/2023\/07\/18\/volleyup-acquaviva-serie-c-femminile-affidata-a-mister-signorile-la-guida-tecnica\/"},"modified":"2023-07-18T18:26:09","modified_gmt":"2023-07-18T18:26:09","slug":"volleyup-acquaviva-serie-c-femminile-affidata-a-mister-signorile-la-guida-tecnica","status":"publish","type":"post","link":"https:\/\/lavocedelpaese.info\/index.php\/2023\/07\/18\/volleyup-acquaviva-serie-c-femminile-affidata-a-mister-signorile-la-guida-tecnica\/","title":{"rendered":"Volleyup Acquaviva, Serie C femminile: affidata a Mister Signorile la guida tecnica"},"content":{"rendered":"<p>\u00a0<\/p>\n<p>\u200b\u00a0<\/p>\n<p>\u200bAcquaviva \u2013 La Voce del Paese\u00a0<\/p>\n<p>La dirigenza della VOLLEYUP non ha avuto alcun dubbio: L\u2019allenatore della formazione delle libellule per la stagione 2023\/2024 nel massimo campionato regionale sar\u00e0 mister Antonello Signorile.<\/p>\n<p>Allenatore di 2\u00b0 grado 3 livello giovanile, \u00e8 stato prima <em>scoutman<\/em> e poi, per tre anni consecutivi, il vice allenatore delle grandi libellule, affiancando prima mister Beppe Fanelli ed infine mister Lino Paolicchio.<\/p>\n<p>Lo scorso anno, dopo le dimissioni di coach Paolicchio, nel Campionato di serie C Femminile, mister Signorile ha guidato in maniera impeccabile le grandi libellule conquistando la salvezza diretta con due giornate d\u2019anticipo ed evitando la complicata lotteria dei play out retrocessione.<\/p>\n<p>Un riconoscimento tanto obbligato quanto guadagnato per il giovane ed apprezzato tecnico acquavivese che, tra l\u2019altro, ha maturato importante esperienza anche grazie ai vari <em>stage<\/em> del progetto pallavolistico \u201c<strong>CLUB ITALIA PER IL SUD\u201d<\/strong>, avviato dalla Federazione Italiana Pallavolo.<\/p>\n<p><a><\/a> \u201c<em>Sono molto entusiasta e onorato per questa nuova esperienza come primo allenatore: \u00e8 per me una grande occasione. Conosco molto bene il gruppo squadra che la societ\u00e0 sta allestendo e sono molto fiducioso. Certamente le atlete daranno il massimo anche questa stagione per raggiungere tutti gli obbiettivi che la dirigenza si \u00e8 prefissati<\/em>\u201d, queste le parole del tecnico targato VOLLEYUP, Antonello Signorile.<\/p>\n<p><a class=\"a2a_button_facebook\" href=\"https:\/\/www.addtoany.com\/add_to\/facebook?linkurl=https%3A%2F%2Facquaviva.lavocedelpaese.info%2Findex.php%2F2023%2F07%2F18%2Fvolleyup-acquaviva-serie-c-femminile-affidata-a-mister-signorile-la-guida-tecnica%2F&amp;linkname=Volleyup%20Acquaviva%2C%20Serie%20C%20femminile%3A%20affidata%20a%20Mister%20Signorile%20la%20guida%20tecnica\" title=\"Facebook\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_twitter\" href=\"https:\/\/www.addtoany.com\/add_to\/twitter?linkurl=https%3A%2F%2Facquaviva.lavocedelpaese.info%2Findex.php%2F2023%2F07%2F18%2Fvolleyup-acquaviva-serie-c-femminile-affidata-a-mister-signorile-la-guida-tecnica%2F&amp;linkname=Volleyup%20Acquaviva%2C%20Serie%20C%20femminile%3A%20affidata%20a%20Mister%20Signorile%20la%20guida%20tecnica\" title=\"Twitter\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_whatsapp\" href=\"https:\/\/www.addtoany.com\/add_to\/whatsapp?linkurl=https%3A%2F%2Facquaviva.lavocedelpaese.info%2Findex.php%2F2023%2F07%2F18%2Fvolleyup-acquaviva-serie-c-femminile-affidata-a-mister-signorile-la-guida-tecnica%2F&amp;linkname=Volleyup%20Acquaviva%2C%20Serie%20C%20femminile%3A%20affidata%20a%20Mister%20Signorile%20la%20guida%20tecnica\" title=\"WhatsApp\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_telegram\" href=\"https:\/\/www.addtoany.com\/add_to\/telegram?linkurl=https%3A%2F%2Facquaviva.lavocedelpaese.info%2Findex.php%2F2023%2F07%2F18%2Fvolleyup-acquaviva-serie-c-femminile-affidata-a-mister-signorile-la-guida-tecnica%2F&amp;linkname=Volleyup%20Acquaviva%2C%20Serie%20C%20femminile%3A%20affidata%20a%20Mister%20Signorile%20la%20guida%20tecnica\" title=\"Telegram\" target=\"_blank\" rel=\"noopener\"><\/a><a class=\"a2a_button_email\" href=\"https:\/\/www.addtoany.com\/add_to\/email?linkurl=https%3A%2F%2Facquaviva.lavocedelpaese.info%2Findex.php%2F2023%2F07%2F18%2Fvolleyup-acquaviva-serie-c-femminile-affidata-a-mister-signorile-la-guida-tecnica%2F&amp;linkname=Volleyup%20Acquaviva%2C%20Serie%20C%20femminile%3A%20affidata%20a%20Mister%20Signorile%20la%20guida%20tecnica\" title=\"Email\" target=\"_blank\" rel=\"noopener\"><\/a><\/p>\n<p>\u00a0<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u200b\u00a0 \u200bAcquaviva \u2013 La Voce del Paese\u00a0 La dirigenza della VOLLEYUP non ha avuto alcun dubbio: L\u2019allenatore della formazione<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[33],"tags":[],"class_list":["post-1764","post","type-post","status-publish","format-standard","hentry","category-network"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Volleyup Acquaviva, Serie C femminile: affidata a Mister Signorile la guida tecnica - La Voce del Paese<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lavocedelpaese.info\/index.php\/2023\/07\/18\/volleyup-acquaviva-serie-c-femminile-affidata-a-mister-signorile-la-guida-tecnica\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Volleyup Acquaviva, Serie C femminile: affidata a Mister Signorile la guida tecnica - La Voce del Paese\" \/>\n<meta property=\"og:description\" content=\"\u00a0 \u200b\u00a0 \u200bAcquaviva \u2013 La Voce del Paese\u00a0 La dirigenza della VOLLEYUP non ha avuto alcun dubbio: L\u2019allenatore della formazione\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lavocedelpaese.info\/index.php\/2023\/07\/18\/volleyup-acquaviva-serie-c-femminile-affidata-a-mister-signorile-la-guida-tecnica\/\" \/>\n<meta property=\"og:site_name\" content=\"La Voce del Paese\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/lavocedelpaese.info\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-18T18:26:09+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/2023\\\/07\\\/18\\\/volleyup-acquaviva-serie-c-femminile-affidata-a-mister-signorile-la-guida-tecnica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/2023\\\/07\\\/18\\\/volleyup-acquaviva-serie-c-femminile-affidata-a-mister-signorile-la-guida-tecnica\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Volleyup Acquaviva, Serie C femminile: affidata a Mister Signorile la guida tecnica\",\"datePublished\":\"2023-07-18T18:26:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/2023\\\/07\\\/18\\\/volleyup-acquaviva-serie-c-femminile-affidata-a-mister-signorile-la-guida-tecnica\\\/\"},\"wordCount\":215,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/#organization\"},\"articleSection\":[\"network\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/2023\\\/07\\\/18\\\/volleyup-acquaviva-serie-c-femminile-affidata-a-mister-signorile-la-guida-tecnica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/2023\\\/07\\\/18\\\/volleyup-acquaviva-serie-c-femminile-affidata-a-mister-signorile-la-guida-tecnica\\\/\",\"url\":\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/2023\\\/07\\\/18\\\/volleyup-acquaviva-serie-c-femminile-affidata-a-mister-signorile-la-guida-tecnica\\\/\",\"name\":\"Volleyup Acquaviva, Serie C femminile: affidata a Mister Signorile la guida tecnica - La Voce del Paese\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/#website\"},\"datePublished\":\"2023-07-18T18:26:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/2023\\\/07\\\/18\\\/volleyup-acquaviva-serie-c-femminile-affidata-a-mister-signorile-la-guida-tecnica\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/2023\\\/07\\\/18\\\/volleyup-acquaviva-serie-c-femminile-affidata-a-mister-signorile-la-guida-tecnica\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/2023\\\/07\\\/18\\\/volleyup-acquaviva-serie-c-femminile-affidata-a-mister-signorile-la-guida-tecnica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lavocedelpaese.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Volleyup Acquaviva, Serie C femminile: affidata a Mister Signorile la guida tecnica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/#website\",\"url\":\"https:\\\/\\\/lavocedelpaese.info\\\/\",\"name\":\"La Voce del Paese\",\"description\":\"Un network di idee\",\"publisher\":{\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lavocedelpaese.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/#organization\",\"name\":\"La Voce del Paese\",\"url\":\"https:\\\/\\\/lavocedelpaese.info\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-logo-150-127.png\",\"contentUrl\":\"https:\\\/\\\/lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-logo-150-127.png\",\"width\":137,\"height\":119,\"caption\":\"La Voce del Paese\"},\"image\":{\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/lavocedelpaese.info\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Volleyup Acquaviva, Serie C femminile: affidata a Mister Signorile la guida tecnica - La Voce del Paese","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lavocedelpaese.info\/index.php\/2023\/07\/18\/volleyup-acquaviva-serie-c-femminile-affidata-a-mister-signorile-la-guida-tecnica\/","og_locale":"it_IT","og_type":"article","og_title":"Volleyup Acquaviva, Serie C femminile: affidata a Mister Signorile la guida tecnica - La Voce del Paese","og_description":"\u00a0 \u200b\u00a0 \u200bAcquaviva \u2013 La Voce del Paese\u00a0 La dirigenza della VOLLEYUP non ha avuto alcun dubbio: L\u2019allenatore della formazione","og_url":"https:\/\/lavocedelpaese.info\/index.php\/2023\/07\/18\/volleyup-acquaviva-serie-c-femminile-affidata-a-mister-signorile-la-guida-tecnica\/","og_site_name":"La Voce del Paese","article_publisher":"https:\/\/www.facebook.com\/lavocedelpaese.info","article_published_time":"2023-07-18T18:26:09+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lavocedelpaese.info\/index.php\/2023\/07\/18\/volleyup-acquaviva-serie-c-femminile-affidata-a-mister-signorile-la-guida-tecnica\/#article","isPartOf":{"@id":"https:\/\/lavocedelpaese.info\/index.php\/2023\/07\/18\/volleyup-acquaviva-serie-c-femminile-affidata-a-mister-signorile-la-guida-tecnica\/"},"author":{"name":"","@id":""},"headline":"Volleyup Acquaviva, Serie C femminile: affidata a Mister Signorile la guida tecnica","datePublished":"2023-07-18T18:26:09+00:00","mainEntityOfPage":{"@id":"https:\/\/lavocedelpaese.info\/index.php\/2023\/07\/18\/volleyup-acquaviva-serie-c-femminile-affidata-a-mister-signorile-la-guida-tecnica\/"},"wordCount":215,"commentCount":0,"publisher":{"@id":"https:\/\/lavocedelpaese.info\/#organization"},"articleSection":["network"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lavocedelpaese.info\/index.php\/2023\/07\/18\/volleyup-acquaviva-serie-c-femminile-affidata-a-mister-signorile-la-guida-tecnica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lavocedelpaese.info\/index.php\/2023\/07\/18\/volleyup-acquaviva-serie-c-femminile-affidata-a-mister-signorile-la-guida-tecnica\/","url":"https:\/\/lavocedelpaese.info\/index.php\/2023\/07\/18\/volleyup-acquaviva-serie-c-femminile-affidata-a-mister-signorile-la-guida-tecnica\/","name":"Volleyup Acquaviva, Serie C femminile: affidata a Mister Signorile la guida tecnica - La Voce del Paese","isPartOf":{"@id":"https:\/\/lavocedelpaese.info\/#website"},"datePublished":"2023-07-18T18:26:09+00:00","breadcrumb":{"@id":"https:\/\/lavocedelpaese.info\/index.php\/2023\/07\/18\/volleyup-acquaviva-serie-c-femminile-affidata-a-mister-signorile-la-guida-tecnica\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lavocedelpaese.info\/index.php\/2023\/07\/18\/volleyup-acquaviva-serie-c-femminile-affidata-a-mister-signorile-la-guida-tecnica\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lavocedelpaese.info\/index.php\/2023\/07\/18\/volleyup-acquaviva-serie-c-femminile-affidata-a-mister-signorile-la-guida-tecnica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lavocedelpaese.info\/"},{"@type":"ListItem","position":2,"name":"Volleyup Acquaviva, Serie C femminile: affidata a Mister Signorile la guida tecnica"}]},{"@type":"WebSite","@id":"https:\/\/lavocedelpaese.info\/#website","url":"https:\/\/lavocedelpaese.info\/","name":"La Voce del Paese","description":"Un network di idee","publisher":{"@id":"https:\/\/lavocedelpaese.info\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lavocedelpaese.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/lavocedelpaese.info\/#organization","name":"La Voce del Paese","url":"https:\/\/lavocedelpaese.info\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/lavocedelpaese.info\/#\/schema\/logo\/image\/","url":"https:\/\/lavocedelpaese.info\/wp-content\/uploads\/2023\/01\/cropped-logo-150-127.png","contentUrl":"https:\/\/lavocedelpaese.info\/wp-content\/uploads\/2023\/01\/cropped-logo-150-127.png","width":137,"height":119,"caption":"La Voce del Paese"},"image":{"@id":"https:\/\/lavocedelpaese.info\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/lavocedelpaese.info"]}]}},"_links":{"self":[{"href":"https:\/\/lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/1764","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/comments?post=1764"}],"version-history":[{"count":0,"href":"https:\/\/lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/1764\/revisions"}],"wp:attachment":[{"href":"https:\/\/lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media?parent=1764"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/categories?post=1764"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/tags?post=1764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}