{"id":11016,"date":"2026-05-27T11:15:21","date_gmt":"2026-05-27T11:15:21","guid":{"rendered":"https:\/\/lavocedelpaese.info\/index.php\/2026\/05\/27\/e-in-edicola-il-nuovo-numero-de-la-voce-del-paese-104\/"},"modified":"2026-05-27T11:15:21","modified_gmt":"2026-05-27T11:15:21","slug":"e-in-edicola-il-nuovo-numero-de-la-voce-del-paese-104","status":"publish","type":"post","link":"https:\/\/lavocedelpaese.info\/index.php\/2026\/05\/27\/e-in-edicola-il-nuovo-numero-de-la-voce-del-paese-104\/","title":{"rendered":"\u00c8 in edicola il nuovo numero de \u201cLa voce del paese\u201d\u00a0\u200b"},"content":{"rendered":"<p>\u00a0<\/p>\n<p>\u200b\u00a0<\/p>\n<p>\u200b\u00a0<\/p>\n<p><strong>Qui sotto tutte le novit\u00e0 presenti in questo numero. Buona lettura a tutti.<\/strong><\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-7799 alignleft\" src=\"https:\/\/gioia.lavocedelpaese.info\/wp-content\/uploads\/2026\/05\/Edicole-Gioia-20.jpg\" alt=\"\" width=\"400\" height=\"554\" \/>L\u2019Editoriale: I minori, la violenza e la propaganda di Iole Pitarra<\/p>\n<p>Crisi Ex AC Boilers, Decaro e Di Sciascio incontrano Ansaldo Energia<\/p>\n<p>36\u00b0 Stormo \u2013 Esercitazione rifornimento rapido con F-35B<\/p>\n<p>La solidariet\u00e0 sale in giostra<\/p>\n<p>Paura nei pressi di via Benagiano \u2013 Incendio di sterpaglie minaccia le abitazioni<\/p>\n<p>Fiamma Mastrapasqua torna a \u201cL\u2019Eredit\u00e0\u201d nel torneo dei campioni<\/p>\n<p>Svaligiato il negozio \u201cPrimigi\u201d<\/p>\n<p>Scontro tra tre auto sulla SP 106 pressi del Penny<\/p>\n<p>La discarica che nessuno vuole vedere a due passi dalla scuola<\/p>\n<p>La Golosa di Puglia trionfa agli Italy Food Awards<\/p>\n<p>Pietro Paradiso premiato a Potenza per \u201cSoul &amp; t-shirts\u201d<\/p>\n<p>Dalla Puglia alla Cina \u2013 Il successo internazionale di Greta Lobefaro con il Trio H\u00e9rmes<\/p>\n<p>Una campana per Sofia \u2013 La gioia di Vincenzo Lamanna alias dottor Brillo di SIMBA OdV<\/p>\n<p>Gioia in Fiore \u2013 Il centro storico si tinge di rosa di Dalila Bellacicco<\/p>\n<p>Signori si \u2026Banda! di Paolo Covella<\/p>\n<p>Banda. Scusarsi! E subito!<\/p>\n<p>ANPI \u2013 Mono Carrasco dona la sua arte e tanta speranza di Piera De Giorgi<\/p>\n<p>UTE \u2013 Il recupero della Chiesa di S. Lucia con Mario Vacca<\/p>\n<p>Una serata al Rossini dedicata a Orazio Svelto<\/p>\n<p>Auguri, dottoressa Ilaria Fico!<\/p>\n<p>Mostra per la Chiesetta della Madonna della Croce<\/p>\n<p>Francesco Buccolieri in concerto a Sant\u2019Andrea di Dalila Bellacicco<\/p>\n<p>\u201cParole e note\u201d- Risate e satira dell\u2019ipocondria di Dalila Bellacicco<\/p>\n<p>Fame di senso. Ossessionati dal cibo che ci salva di Mariella Panessa<\/p>\n<p>Trionfo corale per le scuole al concorso \u201cDiversi in versi\u201d<\/p>\n<p>Studenti del corso di Elettronica dell\u2019ITI \u201cG. Galilei\u201d al Concorso Nazionale di Napoli<\/p>\n<p>Via Eva \u2013 \u201cEsplorando la Resistenza e la Costituzione\u201d<\/p>\n<p>\u201cSan Filippo Neri: la gioia che costruisce comunit\u00e0\u201d<\/p>\n<p>\u201cBreakfast Club\u201d per gli alunni della Primaria di Via Eva<\/p>\n<p>Spazi di Pace esplorati dagli studenti del Virgilio<\/p>\n<p>Capire l\u2019Autismo \u2013 In rete tra scuola, famiglia e territorio<\/p>\n<p>L\u2019amicizia e l\u2019inclusione cantate dalla III E della \u201cCarano\u201d<\/p>\n<p>Losapio \u2013 \u201cLa strada non \u00e8 una giungla\u2026 a scuola\u201d<\/p>\n<p>Estate e libri<\/p>\n<p>\u201cPatria\u201d quando la storia divide, l\u2019umanit\u00e0 resta di Grazia Procino<\/p>\n<p>\u201cCon il cuore pieno\u201d \u2013 Alessandra Colucci in \u201cLibri in biblioteca\u201d di Loredana Lippolis<\/p>\n<p>Orto dalla Luna \u2013 Ricerca di lavoro nel segno della biodiversit\u00e0 e della bellezza<\/p>\n<p>Domenica 31 maggio, recita del S. Rosario sul sagrato di S. Domenico<\/p>\n<p>Caleidoscopio notturno di Ninn\u00ec Rizzi<\/p>\n<p>\u201cLa Poesia della settimana\u201d a cura di Giacomo Leronni<\/p>\n<p>Alchimia delle emozioni di Gianna Evangelista<\/p>\n<p>Raccontando in versi di Enzo Diana<\/p>\n<p>Una ventata di poesia di FreshMarina<\/p>\n<p>Il professore (storie di vite e di magie) di Giovanni Vasco<\/p>\n<p>Sport, emozioni e divertimento al Centro Cinofilo Dog Hero<\/p>\n<p>Academy \u2013 Rimonta da urlo contro Cutrofiano<\/p>\n<p>ASD Gioia&amp;Ritmica \u2013 Tre podi al Regionale a Castellana<\/p>\n<p>Centro Sportivo Padre Semeria \u2013 Rising Stars Padel Tour U16<\/p>\n<p><a class=\"a2a_button_facebook\" href=\"https:\/\/www.addtoany.com\/add_to\/facebook?linkurl=https%3A%2F%2Fgioia.lavocedelpaese.info%2Findex.php%2F2026%2F05%2F27%2Fe-in-edicola-il-nuovo-numero-de-la-voce-del-paese-157%2F&amp;linkname=%C3%88%20in%20edicola%20il%20nuovo%20numero%20de%20%E2%80%9CLa%20voce%20del%20paese%E2%80%9D\" title=\"Facebook\" rel=\"nofollow noopener\" target=\"_blank\"><\/a><a class=\"a2a_button_twitter\" href=\"https:\/\/www.addtoany.com\/add_to\/twitter?linkurl=https%3A%2F%2Fgioia.lavocedelpaese.info%2Findex.php%2F2026%2F05%2F27%2Fe-in-edicola-il-nuovo-numero-de-la-voce-del-paese-157%2F&amp;linkname=%C3%88%20in%20edicola%20il%20nuovo%20numero%20de%20%E2%80%9CLa%20voce%20del%20paese%E2%80%9D\" title=\"Twitter\" rel=\"nofollow noopener\" target=\"_blank\"><\/a><a class=\"a2a_button_whatsapp\" href=\"https:\/\/www.addtoany.com\/add_to\/whatsapp?linkurl=https%3A%2F%2Fgioia.lavocedelpaese.info%2Findex.php%2F2026%2F05%2F27%2Fe-in-edicola-il-nuovo-numero-de-la-voce-del-paese-157%2F&amp;linkname=%C3%88%20in%20edicola%20il%20nuovo%20numero%20de%20%E2%80%9CLa%20voce%20del%20paese%E2%80%9D\" title=\"WhatsApp\" rel=\"nofollow noopener\" target=\"_blank\"><\/a><a class=\"a2a_button_telegram\" href=\"https:\/\/www.addtoany.com\/add_to\/telegram?linkurl=https%3A%2F%2Fgioia.lavocedelpaese.info%2Findex.php%2F2026%2F05%2F27%2Fe-in-edicola-il-nuovo-numero-de-la-voce-del-paese-157%2F&amp;linkname=%C3%88%20in%20edicola%20il%20nuovo%20numero%20de%20%E2%80%9CLa%20voce%20del%20paese%E2%80%9D\" title=\"Telegram\" rel=\"nofollow noopener\" target=\"_blank\"><\/a><a class=\"a2a_button_email\" href=\"https:\/\/www.addtoany.com\/add_to\/email?linkurl=https%3A%2F%2Fgioia.lavocedelpaese.info%2Findex.php%2F2026%2F05%2F27%2Fe-in-edicola-il-nuovo-numero-de-la-voce-del-paese-157%2F&amp;linkname=%C3%88%20in%20edicola%20il%20nuovo%20numero%20de%20%E2%80%9CLa%20voce%20del%20paese%E2%80%9D\" title=\"Email\" rel=\"nofollow noopener\" target=\"_blank\"><\/a><\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u200b\u00a0\u00a0\u00a0<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u200b\u00a0 \u200b\u00a0 Qui sotto tutte le novit\u00e0 presenti in questo numero. Buona lettura a tutti. L\u2019Editoriale: I minori, la<\/p>\n","protected":false},"author":6,"featured_media":8020,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[33],"tags":[],"class_list":["post-11016","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-network"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c8 in edicola il nuovo numero de \u201cLa voce del paese\u201d\u00a0\u200b - La Voce del Paese<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lavocedelpaese.info\/index.php\/2026\/05\/27\/e-in-edicola-il-nuovo-numero-de-la-voce-del-paese-104\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c8 in edicola il nuovo numero de \u201cLa voce del paese\u201d\u00a0\u200b - La Voce del Paese\" \/>\n<meta property=\"og:description\" content=\"\u00a0 \u200b\u00a0 \u200b\u00a0 Qui sotto tutte le novit\u00e0 presenti in questo numero. Buona lettura a tutti. L\u2019Editoriale: I minori, la\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lavocedelpaese.info\/index.php\/2026\/05\/27\/e-in-edicola-il-nuovo-numero-de-la-voce-del-paese-104\/\" \/>\n<meta property=\"og:site_name\" content=\"La Voce del Paese\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/lavocedelpaese.info\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-27T11:15:21+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/2026\\\/05\\\/27\\\/e-in-edicola-il-nuovo-numero-de-la-voce-del-paese-104\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/2026\\\/05\\\/27\\\/e-in-edicola-il-nuovo-numero-de-la-voce-del-paese-104\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/#\\\/schema\\\/person\\\/ec151d321306bd7591f7a061abf72d88\"},\"headline\":\"\u00c8 in edicola il nuovo numero de \u201cLa voce del paese\u201d\u00a0\u200b\",\"datePublished\":\"2026-05-27T11:15:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/2026\\\/05\\\/27\\\/e-in-edicola-il-nuovo-numero-de-la-voce-del-paese-104\\\/\"},\"wordCount\":469,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/2026\\\/05\\\/27\\\/e-in-edicola-il-nuovo-numero-de-la-voce-del-paese-104\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Edicole-Gioia-36-bfHYC0.png\",\"articleSection\":[\"network\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/2026\\\/05\\\/27\\\/e-in-edicola-il-nuovo-numero-de-la-voce-del-paese-104\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/2026\\\/05\\\/27\\\/e-in-edicola-il-nuovo-numero-de-la-voce-del-paese-104\\\/\",\"url\":\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/2026\\\/05\\\/27\\\/e-in-edicola-il-nuovo-numero-de-la-voce-del-paese-104\\\/\",\"name\":\"\u00c8 in edicola il nuovo numero de \u201cLa voce del paese\u201d\u00a0\u200b - La Voce del Paese\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/2026\\\/05\\\/27\\\/e-in-edicola-il-nuovo-numero-de-la-voce-del-paese-104\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/2026\\\/05\\\/27\\\/e-in-edicola-il-nuovo-numero-de-la-voce-del-paese-104\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Edicole-Gioia-36-bfHYC0.png\",\"datePublished\":\"2026-05-27T11:15:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/2026\\\/05\\\/27\\\/e-in-edicola-il-nuovo-numero-de-la-voce-del-paese-104\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/2026\\\/05\\\/27\\\/e-in-edicola-il-nuovo-numero-de-la-voce-del-paese-104\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/2026\\\/05\\\/27\\\/e-in-edicola-il-nuovo-numero-de-la-voce-del-paese-104\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Edicole-Gioia-36-bfHYC0.png\",\"contentUrl\":\"https:\\\/\\\/lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Edicole-Gioia-36-bfHYC0.png\",\"width\":1200,\"height\":1670},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/2026\\\/05\\\/27\\\/e-in-edicola-il-nuovo-numero-de-la-voce-del-paese-104\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lavocedelpaese.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c8 in edicola il nuovo numero de \u201cLa voce del paese\u201d\u00a0\u200b\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/#website\",\"url\":\"https:\\\/\\\/lavocedelpaese.info\\\/\",\"name\":\"La Voce del Paese\",\"description\":\"Un network di idee\",\"publisher\":{\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lavocedelpaese.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/#organization\",\"name\":\"La Voce del Paese\",\"url\":\"https:\\\/\\\/lavocedelpaese.info\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-logo-150-127.png\",\"contentUrl\":\"https:\\\/\\\/lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-logo-150-127.png\",\"width\":137,\"height\":119,\"caption\":\"La Voce del Paese\"},\"image\":{\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/lavocedelpaese.info\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/#\\\/schema\\\/person\\\/ec151d321306bd7591f7a061abf72d88\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af8f2caf0663124588de48a9380e07cbc95a74ef15b8062d0d39106c32fe3023?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af8f2caf0663124588de48a9380e07cbc95a74ef15b8062d0d39106c32fe3023?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af8f2caf0663124588de48a9380e07cbc95a74ef15b8062d0d39106c32fe3023?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/lavocedelpaese.info\"],\"url\":\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c8 in edicola il nuovo numero de \u201cLa voce del paese\u201d\u00a0\u200b - La Voce del Paese","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lavocedelpaese.info\/index.php\/2026\/05\/27\/e-in-edicola-il-nuovo-numero-de-la-voce-del-paese-104\/","og_locale":"it_IT","og_type":"article","og_title":"\u00c8 in edicola il nuovo numero de \u201cLa voce del paese\u201d\u00a0\u200b - La Voce del Paese","og_description":"\u00a0 \u200b\u00a0 \u200b\u00a0 Qui sotto tutte le novit\u00e0 presenti in questo numero. Buona lettura a tutti. L\u2019Editoriale: I minori, la","og_url":"https:\/\/lavocedelpaese.info\/index.php\/2026\/05\/27\/e-in-edicola-il-nuovo-numero-de-la-voce-del-paese-104\/","og_site_name":"La Voce del Paese","article_publisher":"https:\/\/www.facebook.com\/lavocedelpaese.info","article_published_time":"2026-05-27T11:15:21+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lavocedelpaese.info\/index.php\/2026\/05\/27\/e-in-edicola-il-nuovo-numero-de-la-voce-del-paese-104\/#article","isPartOf":{"@id":"https:\/\/lavocedelpaese.info\/index.php\/2026\/05\/27\/e-in-edicola-il-nuovo-numero-de-la-voce-del-paese-104\/"},"author":{"name":"admin","@id":"https:\/\/lavocedelpaese.info\/#\/schema\/person\/ec151d321306bd7591f7a061abf72d88"},"headline":"\u00c8 in edicola il nuovo numero de \u201cLa voce del paese\u201d\u00a0\u200b","datePublished":"2026-05-27T11:15:21+00:00","mainEntityOfPage":{"@id":"https:\/\/lavocedelpaese.info\/index.php\/2026\/05\/27\/e-in-edicola-il-nuovo-numero-de-la-voce-del-paese-104\/"},"wordCount":469,"commentCount":0,"publisher":{"@id":"https:\/\/lavocedelpaese.info\/#organization"},"image":{"@id":"https:\/\/lavocedelpaese.info\/index.php\/2026\/05\/27\/e-in-edicola-il-nuovo-numero-de-la-voce-del-paese-104\/#primaryimage"},"thumbnailUrl":"https:\/\/lavocedelpaese.info\/wp-content\/uploads\/2024\/10\/Edicole-Gioia-36-bfHYC0.png","articleSection":["network"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lavocedelpaese.info\/index.php\/2026\/05\/27\/e-in-edicola-il-nuovo-numero-de-la-voce-del-paese-104\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lavocedelpaese.info\/index.php\/2026\/05\/27\/e-in-edicola-il-nuovo-numero-de-la-voce-del-paese-104\/","url":"https:\/\/lavocedelpaese.info\/index.php\/2026\/05\/27\/e-in-edicola-il-nuovo-numero-de-la-voce-del-paese-104\/","name":"\u00c8 in edicola il nuovo numero de \u201cLa voce del paese\u201d\u00a0\u200b - La Voce del Paese","isPartOf":{"@id":"https:\/\/lavocedelpaese.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lavocedelpaese.info\/index.php\/2026\/05\/27\/e-in-edicola-il-nuovo-numero-de-la-voce-del-paese-104\/#primaryimage"},"image":{"@id":"https:\/\/lavocedelpaese.info\/index.php\/2026\/05\/27\/e-in-edicola-il-nuovo-numero-de-la-voce-del-paese-104\/#primaryimage"},"thumbnailUrl":"https:\/\/lavocedelpaese.info\/wp-content\/uploads\/2024\/10\/Edicole-Gioia-36-bfHYC0.png","datePublished":"2026-05-27T11:15:21+00:00","breadcrumb":{"@id":"https:\/\/lavocedelpaese.info\/index.php\/2026\/05\/27\/e-in-edicola-il-nuovo-numero-de-la-voce-del-paese-104\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lavocedelpaese.info\/index.php\/2026\/05\/27\/e-in-edicola-il-nuovo-numero-de-la-voce-del-paese-104\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/lavocedelpaese.info\/index.php\/2026\/05\/27\/e-in-edicola-il-nuovo-numero-de-la-voce-del-paese-104\/#primaryimage","url":"https:\/\/lavocedelpaese.info\/wp-content\/uploads\/2024\/10\/Edicole-Gioia-36-bfHYC0.png","contentUrl":"https:\/\/lavocedelpaese.info\/wp-content\/uploads\/2024\/10\/Edicole-Gioia-36-bfHYC0.png","width":1200,"height":1670},{"@type":"BreadcrumbList","@id":"https:\/\/lavocedelpaese.info\/index.php\/2026\/05\/27\/e-in-edicola-il-nuovo-numero-de-la-voce-del-paese-104\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lavocedelpaese.info\/"},{"@type":"ListItem","position":2,"name":"\u00c8 in edicola il nuovo numero de \u201cLa voce del paese\u201d\u00a0\u200b"}]},{"@type":"WebSite","@id":"https:\/\/lavocedelpaese.info\/#website","url":"https:\/\/lavocedelpaese.info\/","name":"La Voce del Paese","description":"Un network di idee","publisher":{"@id":"https:\/\/lavocedelpaese.info\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lavocedelpaese.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/lavocedelpaese.info\/#organization","name":"La Voce del Paese","url":"https:\/\/lavocedelpaese.info\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/lavocedelpaese.info\/#\/schema\/logo\/image\/","url":"https:\/\/lavocedelpaese.info\/wp-content\/uploads\/2023\/01\/cropped-logo-150-127.png","contentUrl":"https:\/\/lavocedelpaese.info\/wp-content\/uploads\/2023\/01\/cropped-logo-150-127.png","width":137,"height":119,"caption":"La Voce del Paese"},"image":{"@id":"https:\/\/lavocedelpaese.info\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/lavocedelpaese.info"]},{"@type":"Person","@id":"https:\/\/lavocedelpaese.info\/#\/schema\/person\/ec151d321306bd7591f7a061abf72d88","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/af8f2caf0663124588de48a9380e07cbc95a74ef15b8062d0d39106c32fe3023?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/af8f2caf0663124588de48a9380e07cbc95a74ef15b8062d0d39106c32fe3023?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/af8f2caf0663124588de48a9380e07cbc95a74ef15b8062d0d39106c32fe3023?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/lavocedelpaese.info"],"url":"https:\/\/lavocedelpaese.info\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/11016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/comments?post=11016"}],"version-history":[{"count":0,"href":"https:\/\/lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/11016\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media\/8020"}],"wp:attachment":[{"href":"https:\/\/lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media?parent=11016"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/categories?post=11016"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/tags?post=11016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}