{"id":10941,"date":"2026-05-08T07:16:29","date_gmt":"2026-05-08T07:16:29","guid":{"rendered":"https:\/\/lavocedelpaese.info\/index.php\/2026\/05\/08\/a-turi-sfida-salvezza-col-corato\/"},"modified":"2026-05-08T07:16:29","modified_gmt":"2026-05-08T07:16:29","slug":"a-turi-sfida-salvezza-col-corato","status":"publish","type":"post","link":"https:\/\/lavocedelpaese.info\/index.php\/2026\/05\/08\/a-turi-sfida-salvezza-col-corato\/","title":{"rendered":"A Turi sfida salvezza col Corato\u00a0\u200b"},"content":{"rendered":"<p>\u00a0<\/p>\n<p>\u200b\u00a0<\/p>\n<p>\u200b\u00a0<\/p>\n<div><\/div>\n<p>Dopo la sosta dello scorso weekend per permettere la disputa della Super Coppa del Sud, che ha visto il Trani trionfare sul Rossano Calabro, torna il Campionato di serie C femminile con la Farmacia Mastrolonardo Turi attesa sabato 9 maggio alle ore 18,30 al Palazzetto di via Cisterna alle 18,30, dove ospiter\u00e0 la Polis Volley Corato, match valido per il penultimo turno della regular season.<\/p>\n<p>Dopo le due vittorie di fila contro l\u2019Acquaviva e sul parquet della Don Milani Volley Bari, il team turese \u00e8 chiamato a centrare il tris in una vera e propria sfida permanenza.<\/p>\n<p>Attualmente infatti la Farmacia Mastrolonardo Turi occupa la nona posizione in graduatoria, \u00a0ad una sola lunghezza dalla Primadonna Bari che la precede in classifica ed \u00e8 virtualmente ancora in corsa per il settimo posto finale, che vorrebbe dire salvezza diretta, occupato proprio dal Corato e dal Bisceglie..<\/p>\n<p>Le classificate infatti dall\u2019ottava alla dodicesima posizione a fine torneo dovranno invece disputare la coda dei playout, con le pari classificate del girone leccese, per ottenere la permanenza per il prossimo campionato di serie C femminile.<\/p>\n<p>Sfida dunque che vale doppio ai fini della classifica quella che attende capitan Alejandra Rodriguez, Sofia Coppi e compagne, che poi nell\u2019ultimo turno faranno visita al Valenzano, quart\u2019ultimo della classe. Due incontri pertanto da cui trarre il massimo dei punti possibili, per poi fare i conteggi e provare ad inseguire ancora la salvezza diretta.<\/p>\n<h4 class=\"wp-block-heading\"><strong>CLASSIFICA<\/strong><\/h4>\n<p>Trani 61, Academy Gioia 56, Amatori Bari 49, Barletta 41, Joy Volley Gioia 40, Corato 36, Bisceglie 36, Primadonna Bari 31, <strong>Farmacia Mastrolonardo Turi<\/strong> 30, Valenzano 25, Molfetta 15, Don Milani Bari 12, Acquaviva 0.\u00a0<\/p>\n<p><a class=\"a2a_button_facebook\" href=\"https:\/\/www.addtoany.com\/add_to\/facebook?linkurl=https%3A%2F%2Fturi.lavocedelpaese.info%2Fa-turi-sfida-salvezza-col-corato%2F&amp;linkname=A%20Turi%20sfida%20salvezza%20col%20Corato\" title=\"Facebook\" rel=\"nofollow noopener\" target=\"_blank\"><\/a><a class=\"a2a_button_twitter\" href=\"https:\/\/www.addtoany.com\/add_to\/twitter?linkurl=https%3A%2F%2Fturi.lavocedelpaese.info%2Fa-turi-sfida-salvezza-col-corato%2F&amp;linkname=A%20Turi%20sfida%20salvezza%20col%20Corato\" title=\"Twitter\" rel=\"nofollow noopener\" target=\"_blank\"><\/a><a class=\"a2a_button_whatsapp\" href=\"https:\/\/www.addtoany.com\/add_to\/whatsapp?linkurl=https%3A%2F%2Fturi.lavocedelpaese.info%2Fa-turi-sfida-salvezza-col-corato%2F&amp;linkname=A%20Turi%20sfida%20salvezza%20col%20Corato\" title=\"WhatsApp\" rel=\"nofollow noopener\" target=\"_blank\"><\/a><a class=\"a2a_button_telegram\" href=\"https:\/\/www.addtoany.com\/add_to\/telegram?linkurl=https%3A%2F%2Fturi.lavocedelpaese.info%2Fa-turi-sfida-salvezza-col-corato%2F&amp;linkname=A%20Turi%20sfida%20salvezza%20col%20Corato\" title=\"Telegram\" rel=\"nofollow noopener\" target=\"_blank\"><\/a><a class=\"a2a_button_email\" href=\"https:\/\/www.addtoany.com\/add_to\/email?linkurl=https%3A%2F%2Fturi.lavocedelpaese.info%2Fa-turi-sfida-salvezza-col-corato%2F&amp;linkname=A%20Turi%20sfida%20salvezza%20col%20Corato\" title=\"Email\" rel=\"nofollow noopener\" target=\"_blank\"><\/a><\/p>\n<p>L&#8217;articolo <a href=\"https:\/\/turi.lavocedelpaese.info\/a-turi-sfida-salvezza-col-corato\/\">A Turi sfida salvezza col Corato<\/a> proviene da <a href=\"https:\/\/turi.lavocedelpaese.info\/\">Turi &#8211; La Voce del Paese<\/a>.<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u200b\u00a0\u00a0\u00a0<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00a0 \u200b\u00a0 \u200b\u00a0 Dopo la sosta dello scorso weekend per permettere la disputa della Super Coppa del Sud, che ha<\/p>\n","protected":false},"author":6,"featured_media":730,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[33],"tags":[],"class_list":["post-10941","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-network"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A Turi sfida salvezza col Corato\u00a0\u200b - La Voce del Paese<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lavocedelpaese.info\/index.php\/2026\/05\/08\/a-turi-sfida-salvezza-col-corato\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A Turi sfida salvezza col Corato\u00a0\u200b - La Voce del Paese\" \/>\n<meta property=\"og:description\" content=\"\u00a0 \u200b\u00a0 \u200b\u00a0 Dopo la sosta dello scorso weekend per permettere la disputa della Super Coppa del Sud, che ha\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lavocedelpaese.info\/index.php\/2026\/05\/08\/a-turi-sfida-salvezza-col-corato\/\" \/>\n<meta property=\"og:site_name\" content=\"La Voce del Paese\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/lavocedelpaese.info\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-08T07:16:29+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/2026\\\/05\\\/08\\\/a-turi-sfida-salvezza-col-corato\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/2026\\\/05\\\/08\\\/a-turi-sfida-salvezza-col-corato\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/#\\\/schema\\\/person\\\/ec151d321306bd7591f7a061abf72d88\"},\"headline\":\"A Turi sfida salvezza col Corato\u00a0\u200b\",\"datePublished\":\"2026-05-08T07:16:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/2026\\\/05\\\/08\\\/a-turi-sfida-salvezza-col-corato\\\/\"},\"wordCount\":278,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/2026\\\/05\\\/08\\\/a-turi-sfida-salvezza-col-corato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/logo-150-127.png\",\"articleSection\":[\"network\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/2026\\\/05\\\/08\\\/a-turi-sfida-salvezza-col-corato\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/2026\\\/05\\\/08\\\/a-turi-sfida-salvezza-col-corato\\\/\",\"url\":\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/2026\\\/05\\\/08\\\/a-turi-sfida-salvezza-col-corato\\\/\",\"name\":\"A Turi sfida salvezza col Corato\u00a0\u200b - La Voce del Paese\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/2026\\\/05\\\/08\\\/a-turi-sfida-salvezza-col-corato\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/2026\\\/05\\\/08\\\/a-turi-sfida-salvezza-col-corato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/logo-150-127.png\",\"datePublished\":\"2026-05-08T07:16:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/2026\\\/05\\\/08\\\/a-turi-sfida-salvezza-col-corato\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/2026\\\/05\\\/08\\\/a-turi-sfida-salvezza-col-corato\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/2026\\\/05\\\/08\\\/a-turi-sfida-salvezza-col-corato\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/logo-150-127.png\",\"contentUrl\":\"https:\\\/\\\/lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/logo-150-127.png\",\"width\":150,\"height\":127},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/2026\\\/05\\\/08\\\/a-turi-sfida-salvezza-col-corato\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lavocedelpaese.info\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A Turi sfida salvezza col Corato\u00a0\u200b\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/#website\",\"url\":\"https:\\\/\\\/lavocedelpaese.info\\\/\",\"name\":\"La Voce del Paese\",\"description\":\"Un network di idee\",\"publisher\":{\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lavocedelpaese.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/#organization\",\"name\":\"La Voce del Paese\",\"url\":\"https:\\\/\\\/lavocedelpaese.info\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-logo-150-127.png\",\"contentUrl\":\"https:\\\/\\\/lavocedelpaese.info\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/cropped-logo-150-127.png\",\"width\":137,\"height\":119,\"caption\":\"La Voce del Paese\"},\"image\":{\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/lavocedelpaese.info\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lavocedelpaese.info\\\/#\\\/schema\\\/person\\\/ec151d321306bd7591f7a061abf72d88\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af8f2caf0663124588de48a9380e07cbc95a74ef15b8062d0d39106c32fe3023?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af8f2caf0663124588de48a9380e07cbc95a74ef15b8062d0d39106c32fe3023?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af8f2caf0663124588de48a9380e07cbc95a74ef15b8062d0d39106c32fe3023?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/lavocedelpaese.info\"],\"url\":\"https:\\\/\\\/lavocedelpaese.info\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A Turi sfida salvezza col Corato\u00a0\u200b - La Voce del Paese","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lavocedelpaese.info\/index.php\/2026\/05\/08\/a-turi-sfida-salvezza-col-corato\/","og_locale":"it_IT","og_type":"article","og_title":"A Turi sfida salvezza col Corato\u00a0\u200b - La Voce del Paese","og_description":"\u00a0 \u200b\u00a0 \u200b\u00a0 Dopo la sosta dello scorso weekend per permettere la disputa della Super Coppa del Sud, che ha","og_url":"https:\/\/lavocedelpaese.info\/index.php\/2026\/05\/08\/a-turi-sfida-salvezza-col-corato\/","og_site_name":"La Voce del Paese","article_publisher":"https:\/\/www.facebook.com\/lavocedelpaese.info","article_published_time":"2026-05-08T07:16:29+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lavocedelpaese.info\/index.php\/2026\/05\/08\/a-turi-sfida-salvezza-col-corato\/#article","isPartOf":{"@id":"https:\/\/lavocedelpaese.info\/index.php\/2026\/05\/08\/a-turi-sfida-salvezza-col-corato\/"},"author":{"name":"admin","@id":"https:\/\/lavocedelpaese.info\/#\/schema\/person\/ec151d321306bd7591f7a061abf72d88"},"headline":"A Turi sfida salvezza col Corato\u00a0\u200b","datePublished":"2026-05-08T07:16:29+00:00","mainEntityOfPage":{"@id":"https:\/\/lavocedelpaese.info\/index.php\/2026\/05\/08\/a-turi-sfida-salvezza-col-corato\/"},"wordCount":278,"commentCount":0,"publisher":{"@id":"https:\/\/lavocedelpaese.info\/#organization"},"image":{"@id":"https:\/\/lavocedelpaese.info\/index.php\/2026\/05\/08\/a-turi-sfida-salvezza-col-corato\/#primaryimage"},"thumbnailUrl":"https:\/\/lavocedelpaese.info\/wp-content\/uploads\/2023\/01\/logo-150-127.png","articleSection":["network"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lavocedelpaese.info\/index.php\/2026\/05\/08\/a-turi-sfida-salvezza-col-corato\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lavocedelpaese.info\/index.php\/2026\/05\/08\/a-turi-sfida-salvezza-col-corato\/","url":"https:\/\/lavocedelpaese.info\/index.php\/2026\/05\/08\/a-turi-sfida-salvezza-col-corato\/","name":"A Turi sfida salvezza col Corato\u00a0\u200b - La Voce del Paese","isPartOf":{"@id":"https:\/\/lavocedelpaese.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lavocedelpaese.info\/index.php\/2026\/05\/08\/a-turi-sfida-salvezza-col-corato\/#primaryimage"},"image":{"@id":"https:\/\/lavocedelpaese.info\/index.php\/2026\/05\/08\/a-turi-sfida-salvezza-col-corato\/#primaryimage"},"thumbnailUrl":"https:\/\/lavocedelpaese.info\/wp-content\/uploads\/2023\/01\/logo-150-127.png","datePublished":"2026-05-08T07:16:29+00:00","breadcrumb":{"@id":"https:\/\/lavocedelpaese.info\/index.php\/2026\/05\/08\/a-turi-sfida-salvezza-col-corato\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lavocedelpaese.info\/index.php\/2026\/05\/08\/a-turi-sfida-salvezza-col-corato\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/lavocedelpaese.info\/index.php\/2026\/05\/08\/a-turi-sfida-salvezza-col-corato\/#primaryimage","url":"https:\/\/lavocedelpaese.info\/wp-content\/uploads\/2023\/01\/logo-150-127.png","contentUrl":"https:\/\/lavocedelpaese.info\/wp-content\/uploads\/2023\/01\/logo-150-127.png","width":150,"height":127},{"@type":"BreadcrumbList","@id":"https:\/\/lavocedelpaese.info\/index.php\/2026\/05\/08\/a-turi-sfida-salvezza-col-corato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lavocedelpaese.info\/"},{"@type":"ListItem","position":2,"name":"A Turi sfida salvezza col Corato\u00a0\u200b"}]},{"@type":"WebSite","@id":"https:\/\/lavocedelpaese.info\/#website","url":"https:\/\/lavocedelpaese.info\/","name":"La Voce del Paese","description":"Un network di idee","publisher":{"@id":"https:\/\/lavocedelpaese.info\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lavocedelpaese.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/lavocedelpaese.info\/#organization","name":"La Voce del Paese","url":"https:\/\/lavocedelpaese.info\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/lavocedelpaese.info\/#\/schema\/logo\/image\/","url":"https:\/\/lavocedelpaese.info\/wp-content\/uploads\/2023\/01\/cropped-logo-150-127.png","contentUrl":"https:\/\/lavocedelpaese.info\/wp-content\/uploads\/2023\/01\/cropped-logo-150-127.png","width":137,"height":119,"caption":"La Voce del Paese"},"image":{"@id":"https:\/\/lavocedelpaese.info\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/lavocedelpaese.info"]},{"@type":"Person","@id":"https:\/\/lavocedelpaese.info\/#\/schema\/person\/ec151d321306bd7591f7a061abf72d88","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/af8f2caf0663124588de48a9380e07cbc95a74ef15b8062d0d39106c32fe3023?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/af8f2caf0663124588de48a9380e07cbc95a74ef15b8062d0d39106c32fe3023?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/af8f2caf0663124588de48a9380e07cbc95a74ef15b8062d0d39106c32fe3023?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/lavocedelpaese.info"],"url":"https:\/\/lavocedelpaese.info\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/10941","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/comments?post=10941"}],"version-history":[{"count":0,"href":"https:\/\/lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/10941\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media\/730"}],"wp:attachment":[{"href":"https:\/\/lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media?parent=10941"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/categories?post=10941"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/tags?post=10941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}